{"id":19,"count":1,"description":"","link":"https:\/\/memento-cloud.fr\/blog\/tag\/brevet\/","name":"brevet","slug":"brevet","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Archives des brevet - Le Blog Memento Cloud<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/memento-cloud.fr\/blog\/tag\/brevet\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des brevet - Le Blog Memento Cloud\" \/>\n<meta property=\"og:url\" content=\"https:\/\/memento-cloud.fr\/blog\/tag\/brevet\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Blog Memento Cloud\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/memento-cloud.fr\/blog\/tag\/brevet\/\",\"url\":\"https:\/\/memento-cloud.fr\/blog\/tag\/brevet\/\",\"name\":\"Archives des brevet - Le Blog Memento Cloud\",\"isPartOf\":{\"@id\":\"https:\/\/memento-cloud.fr\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/memento-cloud.fr\/blog\/tag\/brevet\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/memento-cloud.fr\/blog\/tag\/brevet\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/memento-cloud.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"brevet\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/memento-cloud.fr\/blog\/#website\",\"url\":\"https:\/\/memento-cloud.fr\/blog\/\",\"name\":\"Le Blog Memento Cloud\",\"description\":\"La Sauvegarde Cloud sans Datacenter !\",\"publisher\":{\"@id\":\"https:\/\/memento-cloud.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/memento-cloud.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/memento-cloud.fr\/blog\/#organization\",\"name\":\"Le Blog Memento Cloud\",\"url\":\"https:\/\/memento-cloud.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/memento-cloud.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/memento-cloud.fr\/blog\/wp-content\/uploads\/2022\/10\/cropped-Logo_Memento_HD-1.png\",\"contentUrl\":\"https:\/\/memento-cloud.fr\/blog\/wp-content\/uploads\/2022\/10\/cropped-Logo_Memento_HD-1.png\",\"width\":512,\"height\":512,\"caption\":\"Le Blog Memento Cloud\"},\"image\":{\"@id\":\"https:\/\/memento-cloud.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/in\/nr-memento-cloud\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archives des brevet - Le Blog Memento Cloud","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/memento-cloud.fr\/blog\/tag\/brevet\/","og_locale":"fr_FR","og_type":"article","og_title":"Archives des brevet - Le Blog Memento Cloud","og_url":"https:\/\/memento-cloud.fr\/blog\/tag\/brevet\/","og_site_name":"Le Blog Memento Cloud","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/memento-cloud.fr\/blog\/tag\/brevet\/","url":"https:\/\/memento-cloud.fr\/blog\/tag\/brevet\/","name":"Archives des brevet - Le Blog Memento Cloud","isPartOf":{"@id":"https:\/\/memento-cloud.fr\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/memento-cloud.fr\/blog\/tag\/brevet\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/memento-cloud.fr\/blog\/tag\/brevet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/memento-cloud.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"brevet"}]},{"@type":"WebSite","@id":"https:\/\/memento-cloud.fr\/blog\/#website","url":"https:\/\/memento-cloud.fr\/blog\/","name":"Le Blog Memento Cloud","description":"La Sauvegarde Cloud sans Datacenter !","publisher":{"@id":"https:\/\/memento-cloud.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/memento-cloud.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/memento-cloud.fr\/blog\/#organization","name":"Le Blog Memento Cloud","url":"https:\/\/memento-cloud.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/memento-cloud.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/memento-cloud.fr\/blog\/wp-content\/uploads\/2022\/10\/cropped-Logo_Memento_HD-1.png","contentUrl":"https:\/\/memento-cloud.fr\/blog\/wp-content\/uploads\/2022\/10\/cropped-Logo_Memento_HD-1.png","width":512,"height":512,"caption":"Le Blog Memento Cloud"},"image":{"@id":"https:\/\/memento-cloud.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/in\/nr-memento-cloud\/"]}]}},"_links":{"self":[{"href":"https:\/\/memento-cloud.fr\/blog\/wp-json\/wp\/v2\/tags\/19","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/memento-cloud.fr\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/memento-cloud.fr\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/memento-cloud.fr\/blog\/wp-json\/wp\/v2\/posts?tags=19"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}