{"id":323,"date":"2026-01-27T10:05:04","date_gmt":"2026-01-27T09:05:04","guid":{"rendered":"https:\/\/memento-cloud.fr\/blog\/?p=323"},"modified":"2026-01-27T10:05:05","modified_gmt":"2026-01-27T09:05:05","slug":"memento-cloud-brevet-europeen","status":"publish","type":"post","link":"https:\/\/memento-cloud.fr\/blog\/memento-cloud-brevet-europeen\/","title":{"rendered":"Memento Cloud obtient son brevet europ\u00e9en"},"content":{"rendered":"\n<p>Grande nouvelle ! \ud83d\ude80<\/p>\n\n\n\n<p>Apr\u00e8s avoir obtenu le brevet fran\u00e7ais l\u2019ann\u00e9e derni\u00e8re, notre technologie vient de recevoir officiellement son brevet europ\u00e9en \ud83c\uddea\ud83c\uddfa.<\/p>\n\n\n\n<p>C\u2019est le r\u00e9sultat de 5 ans de travail acharn\u00e9, avec cet objectif en ligne de mire.<\/p>\n\n\n\n<p>Pour rappel, <a href=\"https:\/\/memento-cloud.fr\/\">Memento Cloud<\/a> est la solution de sauvegarde de donn\u00e9es qui remplace le stockage en datacenter par la valorisation de l\u2019espace inexploit\u00e9 des organisations.<\/p>\n\n\n\n<p>\ud83d\udc49 Pour une sauvegarde plus souveraine, plus r\u00e9siliente et beaucoup moins gourmande en infrastructure.<\/p>\n\n\n\n<p>Cette \u00e9tape majeure confirme la valeur unique de notre innovation et renforce notre position sur le march\u00e9.<\/p>\n\n\n\n<p>Nous sommes tr\u00e8s fiers de cet accomplissement, qui est avant tout un travail d\u2019\u00e9quipe.<\/p>\n\n\n\n<p>Et ce n\u2019est que le d\u00e9but !<\/p>\n\n\n\n<p>L\u2019ann\u00e9e 2026 sera riche en nouvelles fonctionnalit\u00e9s :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>extension du p\u00e9rim\u00e8tre de sauvegarde,<\/li>\n\n\n\n<li>optimisation accrue des ressources de stockage,<\/li>\n\n\n\n<li>et bien plus encore\u2026<\/li>\n<\/ul>\n\n\n\n<p>Et ce n&rsquo;est pas tout, vous pouvez nous rencontrer :<br>\ud83d\udccd au <a href=\"https:\/\/www.cybershowparis.fr\/\">Cyber Show<\/a> les 28 et 29 Janvier, pour notre premier salon de l&rsquo;ann\u00e9e,<br>\ud83d\udccd au salon <a href=\"https:\/\/www.itpartners.fr\/\">IT Partners<\/a> les 04 et 05 f\u00e9vrier pour renforcer nos partenariats,<br>\ud83d\udccd au <a href=\"https:\/\/europe.forum-incyber.com\/\">Forum InCyber de Lille<\/a> fin mars, o\u00f9 nous pr\u00e9senterons une nouvelle fa\u00e7on de sauvegarder les donn\u00e9es.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Grande nouvelle ! \ud83d\ude80 Apr\u00e8s avoir obtenu le brevet fran\u00e7ais l\u2019ann\u00e9e derni\u00e8re, notre technologie vient de recevoir officiellement son brevet europ\u00e9en \ud83c\uddea\ud83c\uddfa. C\u2019est le r\u00e9sultat de 5 ans de travail acharn\u00e9, avec cet objectif en ligne de mire. Pour rappel, Memento Cloud est la solution de sauvegarde de donn\u00e9es qui remplace le stockage en datacenter &#8230; <a title=\"Memento Cloud obtient son brevet europ\u00e9en\" class=\"read-more\" href=\"https:\/\/memento-cloud.fr\/blog\/memento-cloud-brevet-europeen\/\" aria-label=\"En savoir plus sur Memento Cloud obtient son brevet europ\u00e9en\">Lire la suite<\/a><\/p>\n","protected":false},"author":1,"featured_media":324,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[19,20,13],"class_list":["post-323","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-article-presse","tag-brevet","tag-memento-cloud","tag-sauvegarde-de-donnees"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Memento Cloud obtient son brevet europ\u00e9en - Le Blog Memento Cloud<\/title>\n<meta name=\"description\" content=\"Apr\u00e8s avoir obtenu le brevet fran\u00e7ais l\u2019ann\u00e9e derni\u00e8re, notre technologie vient de recevoir officiellement son brevet europ\u00e9en \ud83c\uddea\ud83c\uddfa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/memento-cloud.fr\/blog\/memento-cloud-brevet-europeen\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Memento Cloud obtient son brevet europ\u00e9en - Le Blog Memento Cloud\" \/>\n<meta property=\"og:description\" content=\"Apr\u00e8s avoir obtenu le brevet fran\u00e7ais l\u2019ann\u00e9e derni\u00e8re, notre technologie vient de recevoir officiellement son brevet europ\u00e9en \ud83c\uddea\ud83c\uddfa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/memento-cloud.fr\/blog\/memento-cloud-brevet-europeen\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Blog Memento Cloud\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-27T09:05:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-27T09:05:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/memento-cloud.fr\/blog\/wp-content\/uploads\/2026\/01\/Post-brevet-EU-1024x683.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nathan Richard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nathan Richard\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/memento-cloud.fr\/blog\/memento-cloud-brevet-europeen\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/memento-cloud.fr\/blog\/memento-cloud-brevet-europeen\/\"},\"author\":{\"name\":\"Nathan Richard\",\"@id\":\"https:\/\/memento-cloud.fr\/blog\/#\/schema\/person\/4746e1a4fd46c29b04002b6352b32332\"},\"headline\":\"Memento Cloud obtient son brevet europ\u00e9en\",\"datePublished\":\"2026-01-27T09:05:04+00:00\",\"dateModified\":\"2026-01-27T09:05:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/memento-cloud.fr\/blog\/memento-cloud-brevet-europeen\/\"},\"wordCount\":213,\"publisher\":{\"@id\":\"https:\/\/memento-cloud.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/memento-cloud.fr\/blog\/memento-cloud-brevet-europeen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/memento-cloud.fr\/blog\/wp-content\/uploads\/2026\/01\/Post-brevet-EU.png\",\"keywords\":[\"brevet\",\"memento cloud\",\"Sauvegarde de donn\u00e9es\"],\"articleSection\":[\"Article presse\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/memento-cloud.fr\/blog\/memento-cloud-brevet-europeen\/\",\"url\":\"https:\/\/memento-cloud.fr\/blog\/memento-cloud-brevet-europeen\/\",\"name\":\"Memento Cloud obtient son brevet europ\u00e9en - Le Blog Memento Cloud\",\"isPartOf\":{\"@id\":\"https:\/\/memento-cloud.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/memento-cloud.fr\/blog\/memento-cloud-brevet-europeen\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/memento-cloud.fr\/blog\/memento-cloud-brevet-europeen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/memento-cloud.fr\/blog\/wp-content\/uploads\/2026\/01\/Post-brevet-EU.png\",\"datePublished\":\"2026-01-27T09:05:04+00:00\",\"dateModified\":\"2026-01-27T09:05:05+00:00\",\"description\":\"Apr\u00e8s avoir obtenu le brevet fran\u00e7ais l\u2019ann\u00e9e derni\u00e8re, notre technologie vient de recevoir officiellement son brevet europ\u00e9en \ud83c\uddea\ud83c\uddfa.\",\"breadcrumb\":{\"@id\":\"https:\/\/memento-cloud.fr\/blog\/memento-cloud-brevet-europeen\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/memento-cloud.fr\/blog\/memento-cloud-brevet-europeen\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/memento-cloud.fr\/blog\/memento-cloud-brevet-europeen\/#primaryimage\",\"url\":\"https:\/\/memento-cloud.fr\/blog\/wp-content\/uploads\/2026\/01\/Post-brevet-EU.png\",\"contentUrl\":\"https:\/\/memento-cloud.fr\/blog\/wp-content\/uploads\/2026\/01\/Post-brevet-EU.png\",\"width\":1536,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/memento-cloud.fr\/blog\/memento-cloud-brevet-europeen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/memento-cloud.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Memento Cloud obtient son brevet europ\u00e9en\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/memento-cloud.fr\/blog\/#website\",\"url\":\"https:\/\/memento-cloud.fr\/blog\/\",\"name\":\"Le Blog Memento Cloud\",\"description\":\"La Sauvegarde Cloud sans Datacenter !\",\"publisher\":{\"@id\":\"https:\/\/memento-cloud.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/memento-cloud.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/memento-cloud.fr\/blog\/#organization\",\"name\":\"Le Blog Memento Cloud\",\"url\":\"https:\/\/memento-cloud.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/memento-cloud.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/memento-cloud.fr\/blog\/wp-content\/uploads\/2022\/10\/cropped-Logo_Memento_HD-1.png\",\"contentUrl\":\"https:\/\/memento-cloud.fr\/blog\/wp-content\/uploads\/2022\/10\/cropped-Logo_Memento_HD-1.png\",\"width\":512,\"height\":512,\"caption\":\"Le Blog Memento Cloud\"},\"image\":{\"@id\":\"https:\/\/memento-cloud.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/in\/nr-memento-cloud\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/memento-cloud.fr\/blog\/#\/schema\/person\/4746e1a4fd46c29b04002b6352b32332\",\"name\":\"Nathan Richard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/memento-cloud.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b9818d13d05f17f5303d7d252ce2bbf6e120c6b47da7c7532f12603f23c709a8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b9818d13d05f17f5303d7d252ce2bbf6e120c6b47da7c7532f12603f23c709a8?s=96&d=mm&r=g\",\"caption\":\"Nathan Richard\"},\"sameAs\":[\"https:\/\/memento-cloud.fr\"],\"url\":\"https:\/\/memento-cloud.fr\/blog\/author\/admin_blog\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Memento Cloud obtient son brevet europ\u00e9en - Le Blog Memento Cloud","description":"Apr\u00e8s avoir obtenu le brevet fran\u00e7ais l\u2019ann\u00e9e derni\u00e8re, notre technologie vient de recevoir officiellement son brevet europ\u00e9en \ud83c\uddea\ud83c\uddfa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/memento-cloud.fr\/blog\/memento-cloud-brevet-europeen\/","og_locale":"fr_FR","og_type":"article","og_title":"Memento Cloud obtient son brevet europ\u00e9en - Le Blog Memento Cloud","og_description":"Apr\u00e8s avoir obtenu le brevet fran\u00e7ais l\u2019ann\u00e9e derni\u00e8re, notre technologie vient de recevoir officiellement son brevet europ\u00e9en \ud83c\uddea\ud83c\uddfa.","og_url":"https:\/\/memento-cloud.fr\/blog\/memento-cloud-brevet-europeen\/","og_site_name":"Le Blog Memento Cloud","article_published_time":"2026-01-27T09:05:04+00:00","article_modified_time":"2026-01-27T09:05:05+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/memento-cloud.fr\/blog\/wp-content\/uploads\/2026\/01\/Post-brevet-EU-1024x683.png","type":"image\/png"}],"author":"Nathan Richard","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Nathan Richard","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/memento-cloud.fr\/blog\/memento-cloud-brevet-europeen\/#article","isPartOf":{"@id":"https:\/\/memento-cloud.fr\/blog\/memento-cloud-brevet-europeen\/"},"author":{"name":"Nathan Richard","@id":"https:\/\/memento-cloud.fr\/blog\/#\/schema\/person\/4746e1a4fd46c29b04002b6352b32332"},"headline":"Memento Cloud obtient son brevet europ\u00e9en","datePublished":"2026-01-27T09:05:04+00:00","dateModified":"2026-01-27T09:05:05+00:00","mainEntityOfPage":{"@id":"https:\/\/memento-cloud.fr\/blog\/memento-cloud-brevet-europeen\/"},"wordCount":213,"publisher":{"@id":"https:\/\/memento-cloud.fr\/blog\/#organization"},"image":{"@id":"https:\/\/memento-cloud.fr\/blog\/memento-cloud-brevet-europeen\/#primaryimage"},"thumbnailUrl":"https:\/\/memento-cloud.fr\/blog\/wp-content\/uploads\/2026\/01\/Post-brevet-EU.png","keywords":["brevet","memento cloud","Sauvegarde de donn\u00e9es"],"articleSection":["Article presse"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/memento-cloud.fr\/blog\/memento-cloud-brevet-europeen\/","url":"https:\/\/memento-cloud.fr\/blog\/memento-cloud-brevet-europeen\/","name":"Memento Cloud obtient son brevet europ\u00e9en - Le Blog Memento Cloud","isPartOf":{"@id":"https:\/\/memento-cloud.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/memento-cloud.fr\/blog\/memento-cloud-brevet-europeen\/#primaryimage"},"image":{"@id":"https:\/\/memento-cloud.fr\/blog\/memento-cloud-brevet-europeen\/#primaryimage"},"thumbnailUrl":"https:\/\/memento-cloud.fr\/blog\/wp-content\/uploads\/2026\/01\/Post-brevet-EU.png","datePublished":"2026-01-27T09:05:04+00:00","dateModified":"2026-01-27T09:05:05+00:00","description":"Apr\u00e8s avoir obtenu le brevet fran\u00e7ais l\u2019ann\u00e9e derni\u00e8re, notre technologie vient de recevoir officiellement son brevet europ\u00e9en \ud83c\uddea\ud83c\uddfa.","breadcrumb":{"@id":"https:\/\/memento-cloud.fr\/blog\/memento-cloud-brevet-europeen\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/memento-cloud.fr\/blog\/memento-cloud-brevet-europeen\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/memento-cloud.fr\/blog\/memento-cloud-brevet-europeen\/#primaryimage","url":"https:\/\/memento-cloud.fr\/blog\/wp-content\/uploads\/2026\/01\/Post-brevet-EU.png","contentUrl":"https:\/\/memento-cloud.fr\/blog\/wp-content\/uploads\/2026\/01\/Post-brevet-EU.png","width":1536,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/memento-cloud.fr\/blog\/memento-cloud-brevet-europeen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/memento-cloud.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Memento Cloud obtient son brevet europ\u00e9en"}]},{"@type":"WebSite","@id":"https:\/\/memento-cloud.fr\/blog\/#website","url":"https:\/\/memento-cloud.fr\/blog\/","name":"Le Blog Memento Cloud","description":"La Sauvegarde Cloud sans Datacenter !","publisher":{"@id":"https:\/\/memento-cloud.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/memento-cloud.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/memento-cloud.fr\/blog\/#organization","name":"Le Blog Memento Cloud","url":"https:\/\/memento-cloud.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/memento-cloud.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/memento-cloud.fr\/blog\/wp-content\/uploads\/2022\/10\/cropped-Logo_Memento_HD-1.png","contentUrl":"https:\/\/memento-cloud.fr\/blog\/wp-content\/uploads\/2022\/10\/cropped-Logo_Memento_HD-1.png","width":512,"height":512,"caption":"Le Blog Memento Cloud"},"image":{"@id":"https:\/\/memento-cloud.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/in\/nr-memento-cloud\/"]},{"@type":"Person","@id":"https:\/\/memento-cloud.fr\/blog\/#\/schema\/person\/4746e1a4fd46c29b04002b6352b32332","name":"Nathan Richard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/memento-cloud.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b9818d13d05f17f5303d7d252ce2bbf6e120c6b47da7c7532f12603f23c709a8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b9818d13d05f17f5303d7d252ce2bbf6e120c6b47da7c7532f12603f23c709a8?s=96&d=mm&r=g","caption":"Nathan Richard"},"sameAs":["https:\/\/memento-cloud.fr"],"url":"https:\/\/memento-cloud.fr\/blog\/author\/admin_blog\/"}]}},"_links":{"self":[{"href":"https:\/\/memento-cloud.fr\/blog\/wp-json\/wp\/v2\/posts\/323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/memento-cloud.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/memento-cloud.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/memento-cloud.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/memento-cloud.fr\/blog\/wp-json\/wp\/v2\/comments?post=323"}],"version-history":[{"count":1,"href":"https:\/\/memento-cloud.fr\/blog\/wp-json\/wp\/v2\/posts\/323\/revisions"}],"predecessor-version":[{"id":325,"href":"https:\/\/memento-cloud.fr\/blog\/wp-json\/wp\/v2\/posts\/323\/revisions\/325"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/memento-cloud.fr\/blog\/wp-json\/wp\/v2\/media\/324"}],"wp:attachment":[{"href":"https:\/\/memento-cloud.fr\/blog\/wp-json\/wp\/v2\/media?parent=323"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/memento-cloud.fr\/blog\/wp-json\/wp\/v2\/categories?post=323"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/memento-cloud.fr\/blog\/wp-json\/wp\/v2\/tags?post=323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}